{"id":1037,"date":"2021-12-12T20:46:36","date_gmt":"2021-12-12T20:46:36","guid":{"rendered":"https:\/\/skm20617.mywhc.ca\/?page_id=1037"},"modified":"2021-12-21T05:47:16","modified_gmt":"2021-12-21T05:47:16","slug":"formulaire-daccueil-transaction-dachat","status":"publish","type":"page","link":"https:\/\/guertinpoirierlaw.ca\/fr\/immobilieres\/formulaire-daccueil-transaction-dachat\/","title":{"rendered":"Formulaire d&rsquo;accueil: Transaction d\u2019achat"},"content":{"rendered":"<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_3' style='display:none'><div id='gf_3' class='gform_anchor' tabindex='-1'><\/div>\n                        <div class='gform_heading'>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>\u00ab\u00a0<span class=\"gfield_required gfield_required_asterisk\">*<\/span>\u00a0\u00bb indique les champs n\u00e9cessaires<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_3'  action='\/fr\/wp-json\/wp\/v2\/pages\/1037#gf_3' data-formid='3' novalidate><input id=\"gpnf_session_hash_3\" type=\"hidden\" name=\"gpnf_session_hash\" value=\"0d211d8217a9\">\n        <div id='gf_progressbar_wrapper_3' class='gf_progressbar_wrapper' data-start-at-zero=''>\n        \t<p class=\"gf_progressbar_title\">\u00c9tape <span class='gf_step_current_page'>1<\/span> sur <span class='gf_step_page_count'>9<\/span><span class='gf_step_page_name'><\/span>\n        \t<\/p>\n            <div class='gf_progressbar gf_progressbar_blue' aria-hidden='true'>\n                <div class='gf_progressbar_percentage percentbar_blue percentbar_11' style='width:11%;'><span>11%<\/span><\/div>\n            <\/div><\/div>\n                        <div class='gform-body gform_body'><div id='gform_page_3_1' class='gform_page ' data-js='page-field-id-0' >\n\t\t\t\t\t<div class='gform_page_fields'><div id='gform_fields_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_94\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_94'>Facebook<\/label><div class='ginput_container'><input name='input_94' id='input_3_94' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_3_94'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/div><div id=\"field_3_63\" class=\"gfield gfield--type-html gfield--width-full gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><p>Toutes nos f\u00e9licitations pour l\u2019achat de votre nouvelle propri\u00e9t\u00e9!<\/p>\n\n<p>Afin de nous assister dans l\u2019ouverture et la pr\u00e9paration de votre dossier, veuillez s\u2019il vous plait nous fournir l\u2019information suivante au sujet de votre transaction.\n<\/p><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                         <input type='button' id='gform_next_button_3_64' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_2' class='gform_page' data-js='page-field-id-64' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_2' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_23\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Vos renseignements personnels<\/h3><\/div><div id=\"field_3_22\" class=\"gfield gfield--type-form gform-theme__no-reset--children field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_22'>Acheteur(s) *<\/label><div class=\"gpnf-nested-entries-container ginput_container\">\n\n\t<table class=\"gpnf-nested-entries\">\n\n\t\t<thead>\n\t\t<tr>\n\t\t\t\t\t\t\t<th scope=\"col\" class=\"gpnf-field-34\">\n\t\t\t\t\tPr\u00e9nom\t\t\t\t<\/th>\n\t\t\t\t\t\t\t<th scope=\"col\" class=\"gpnf-field-35\">\n\t\t\t\t\tDeuxi\u00e8me pr\u00e9nom\t\t\t\t<\/th>\n\t\t\t\t\t\t\t<th scope=\"col\" class=\"gpnf-field-36\">\n\t\t\t\t\tNom de famille\t\t\t\t<\/th>\n\t\t\t\t\t\t<th scope=\"col\" class=\"gpnf-row-actions\"><span class=\"screen-reader-text\">Actions<\/span><\/th>\n\t\t<\/tr>\n\t\t<\/thead>\n\n\t\t<tbody data-bind=\"visible: entries().length, foreach: entries\">\n\t\t<tr data-bind=\"attr: { 'data-entryid': id }\">\n\t\t\t\t\t\t\t<td class=\"gpnf-field\"\n\t\t\t\t\tdata-bind=\"html: f34.label, attr: { 'data-value': f34.label }\"\n\t\t\t\t\tdata-heading=\"Pr\u00e9nom\"\n\t\t\t\t>&nbsp;<\/td>\n\t\t\t\t\t\t\t<td class=\"gpnf-field\"\n\t\t\t\t\tdata-bind=\"html: f35.label, attr: { 'data-value': f35.label }\"\n\t\t\t\t\tdata-heading=\"Deuxi\u00e8me pr\u00e9nom\"\n\t\t\t\t>&nbsp;<\/td>\n\t\t\t\t\t\t\t<td class=\"gpnf-field\"\n\t\t\t\t\tdata-bind=\"html: f36.label, attr: { 'data-value': f36.label }\"\n\t\t\t\t\tdata-heading=\"Nom de famille\"\n\t\t\t\t>&nbsp;<\/td>\n\t\t\t\t\t\t<td class=\"gpnf-row-actions\" style=\"display: none;\" data-bind=\"visible: true\">\n\t\t\t\t<ul>\n\t\t\t\t\t<li class=\"edit\"><button type=\"button\" class=\"edit-button gform-theme-button--secondary\" data-bind=\"click: $parent.editEntry, attr: { 'aria-label': 'Edit un acheteur {0} where Pr\u00e9nom is {1}.'.gformFormat( $index() + 1, f34.label ) }\">Modifier<\/button><\/li>\n\t\t\t\t\t\t\t\t\t\t<li class=\"delete\"><button type=\"button\" class=\"delete-button gform-theme-button--simple gform-theme-button--size-md\" data-bind=\"click: $parent.deleteEntry, attr: { 'aria-label': 'Delete un acheteur {0} where Pr\u00e9nom is {1}.'.gformFormat( $index() + 1, f34.label ) }\">Supprimer<\/button><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<\/tbody>\n\n\t\t<tbody data-bind=\"visible: entries().length <= 0\">\n\t\t<tr class=\"gpnf-no-entries\" data-bind=\"visible: entries().length <= 0\" style=\"display: none;\">\n\t\t\t<td colspan=\"4\">\n\t\t\t\tIl n\u2019y a aucun(e) <span>records.<\/span>\t\t\t<\/td>\n\t\t<\/tr>\n\t\t<\/tbody>\n\n\t<\/table>\n\n\t<button type=\"button\" class=\"gpnf-add-entry\"\n\t\t        data-formid=\"3\"\n\t\t        data-nestedformid=\"2\"\n\t\t\t\tdata-bind=\"attr: { disabled: isMaxed }, css: { 'gf-default-disabled': isMaxed }\"\n\t\t\t\t>\n\t\t\t\tAjouter un acheteur\n\t\t\t<\/button>\t\n\t\t\t<p class=\"gpnf-add-entry-max\" data-bind=\"visible: isMaxed\" style=\"display: none;\">\n\t\t\t\tLe nombre maximal a \u00e9t\u00e9 atteint.\n\t\t\t<\/p>\n<\/div>\n<input type=\"hidden\"\n                name=\"input_22\"\n                id=\"input_3_22\"\n                data-bind=\"value: entryIds\"\n                value=\"\" \/><\/div><div id=\"field_3_58\" class=\"gfield gfield--type-html gfield--width-full gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  >Utilisez le bouton <em>Ajouter un acheteur<\/em> et donnez nous l'information sur chaque individu \u00e0 \u00eatre enregistr\u00e9 sur le titre.<\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <input type='button' id='gform_previous_button_3_54' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='pr\u00e9c\u00e9dent'  \/> <input type='button' id='gform_next_button_3_54' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_3' class='gform_page' data-js='page-field-id-54' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_24\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Au sujet de votre transaction<\/h3><\/div><div id=\"field_3_25\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><strong>Quel est le nom, le num\u00e9ro de t\u00e9l\u00e9phone et\/ou l\u2019adresse courriel de votre agent immobilier, si applicable?<\/strong><\/div><div id=\"field_3_65\" class=\"gfield gfield--type-text gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_65'>Nom:<\/label><div class='ginput_container ginput_container_text'><input name='input_65' id='input_3_65' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_27\" class=\"gfield gfield--type-phone gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_27'>Num\u00e9ro de t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_phone'><input name='input_27' id='input_3_27' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_28\" class=\"gfield gfield--type-email gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_28'>Adresse courriel:<\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_28' id='input_3_28' type='email' value='' class='large'     aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_3_29\" class=\"gfield gfield--type-textarea gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_29'>Autres informations:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_29' id='input_3_29' class='textarea small'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <input type='button' id='gform_previous_button_3_83' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='pr\u00e9c\u00e9dent'  \/> <input type='button' id='gform_next_button_3_83' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_4' class='gform_page' data-js='page-field-id-83' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_4' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_92\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Au sujet de votre transaction<\/h3><\/div><div id=\"field_3_84\" class=\"gfield gfield--type-html gfield--width-full gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><strong>Certaines transactions immobili\u00e8res sont facilit\u00e9es par des fournisseurs de services, tels que RCMP, Brookfield ou TransferEase (par exemples). <strong><\/div><div id=\"field_3_79\" class=\"gfield gfield--type-select gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_79'>Votre transaction est elle facilit\u00e9 par un fournisseur de services (BGRS, TransferEase, etc.)?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_79' id='input_3_79' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' ><\/option><option value='Oui' >Oui<\/option><option value='Non' >Non<\/option><\/select><\/div><\/div><div id=\"field_3_85\" class=\"gfield gfield--type-select gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_85'>Quel fournisseur de services vous assiste avec cette transaction:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_85' id='input_3_85' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' ><\/option><option value='TransferEase' >TransferEase<\/option><option value='Brookfield (BGRS)' >Brookfield (BGRS)<\/option><option value='GRC' >GRC<\/option><\/select><\/div><\/div><div id=\"field_3_87\" class=\"gfield gfield--type-html gfield--width-full gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  >Notre bureau sera contact\u00e9 directement par TransferEase. Aucune autre action n'est requise de votre part. <\/div><div id=\"field_3_93\" class=\"gfield gfield--type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_93'>Lequel des acheteurs est un membre de BGRS (veuillez fournir le pr\u00e9nom):<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_93' id='input_3_93' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_80\" class=\"gfield gfield--type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_80'>Veuillez fournir le num\u00e9ro de r\u00e9f\u00e9rence BGRS du membre:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_80' id='input_3_80' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_88\" class=\"gfield gfield--type-select gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_88'>Le membre est-il un(e) employ\u00e9(e) du TBS ou des FAC?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_88' id='input_3_88' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' ><\/option><option value='TBS' >TBS<\/option><option value='FAC' >FAC<\/option><\/select><\/div><\/div><div id=\"field_3_81\" class=\"gfield gfield--type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_81'>Veuillez fournir l&#039;adresse courriel de votre personne contacte de la GRC:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_81' id='input_3_81' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <input type='button' id='gform_previous_button_3_66' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='pr\u00e9c\u00e9dent'  \/> <input type='button' id='gform_next_button_3_66' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_5' class='gform_page' data-js='page-field-id-66' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_5' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_69\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Au sujet de votre transaction<\/h3><\/div><div id=\"field_3_62\" class=\"gfield gfield--type-date gfield--input-type-datepicker gfield--datepicker-no-icon gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_62'>Quelle est la date de cl\u00f4ture de votre transaction (jour\/mois\/ann\u00e9e)?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_date'>\n                            <input name='input_62' id='input_3_62' type='text' value='' class='datepicker gform-datepicker dmy datepicker_no_icon gdatepicker-no-icon'   placeholder='jj\/mm\/aaaa' aria-describedby=\"input_3_62_date_format\" aria-invalid=\"false\" aria-required=\"true\"\/>\n                            <span id='input_3_62_date_format' class='screen-reader-text'>JJ slash MM slash AAAA<\/span>\n                        <\/div>\n                        <input type='hidden' id='gforms_calendar_icon_input_3_62' class='gform_hidden' value='https:\/\/guertinpoirierlaw.ca\/wp-content\/plugins\/gravityforms\/images\/datepicker\/datepicker.svg'\/><\/div><fieldset id=\"field_3_30\" class=\"gfield gfield--type-address gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Quelle est l\u2019adresse de la propri\u00e9t\u00e9 achet\u00e9e, incluant la ville et le code postal (si disponibles)?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend>    \n                    <div class='ginput_complex ginput_container has_street has_city has_state has_zip ginput_container_address gform-grid-row' id='input_3_30' >\n                         <span class='ginput_full address_line_1 ginput_address_line_1 gform-grid-col' id='input_3_30_1_container' >\n                                        <input type='text' name='input_30.1' id='input_3_30_1' value=''    aria-required='true'    \/>\n                                        <label for='input_3_30_1' id='input_3_30_1_label' class='gform-field-label gform-field-label--type-sub '>Adresse postale<\/label>\n                                    <\/span><span class='ginput_left address_city ginput_address_city gform-grid-col' id='input_3_30_3_container' >\n                                    <input type='text' name='input_30.3' id='input_3_30_3' value=''    aria-required='true'    \/>\n                                    <label for='input_3_30_3' id='input_3_30_3_label' class='gform-field-label gform-field-label--type-sub '>Ville<\/label>\n                                 <\/span><span class='ginput_right address_state ginput_address_state gform-grid-col' id='input_3_30_4_container' >\n                                        <select name='input_30.4' id='input_3_30_4'     aria-required='true'    ><option value='' ><\/option><option value='Alberta' >Alberta<\/option><option value='Colombie-Britannique' >Colombie-Britannique<\/option><option value='Manitoba' >Manitoba<\/option><option value='Nouveau-Brunswick' >Nouveau-Brunswick<\/option><option value='Terre-Neuve-et-Labrador' >Terre-Neuve-et-Labrador<\/option><option value='Territoires du Nord-Ouest' >Territoires du Nord-Ouest<\/option><option value='Nouvelle-\u00c9cosse' >Nouvelle-\u00c9cosse<\/option><option value='Nunavut' >Nunavut<\/option><option value='Ontario' selected='selected'>Ontario<\/option><option value='\u00cele du Prince-\u00c9douard' >\u00cele du Prince-\u00c9douard<\/option><option value='Qu\u00e9bec' >Qu\u00e9bec<\/option><option value='Saskatchewan' >Saskatchewan<\/option><option value='Yukon' >Yukon<\/option><\/select>\n                                        <label for='input_3_30_4' id='input_3_30_4_label' class='gform-field-label gform-field-label--type-sub '>Province<\/label>\n                                      <\/span><span class='ginput_left address_zip ginput_address_zip gform-grid-col' id='input_3_30_5_container' >\n                                    <input type='text' name='input_30.5' id='input_3_30_5' value=''    aria-required='true'    \/>\n                                    <label for='input_3_30_5' id='input_3_30_5_label' class='gform-field-label gform-field-label--type-sub '>Code postal<\/label>\n                                <\/span><input type='hidden' class='gform_hidden' name='input_30.6' id='input_3_30_6' value='Canada' \/>\n                    <div class='gf_clear gf_clear_complex'><\/div>\n                <\/div><\/fieldset><div id=\"field_3_31\" class=\"gfield gfield--type-select gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_31'>La propri\u00e9t\u00e9 achet\u00e9e est-elle une nouvelle construction ou une maison de revente?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_31' id='input_3_31' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' ><\/option><option value='nouvelle construction' >nouvelle construction<\/option><option value='maison de revente' >maison de revente<\/option><\/select><\/div><\/div><div id=\"field_3_32\" class=\"gfield gfield--type-select gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_32'>Quel est le type de propri\u00e9t\u00e9 achet\u00e9e?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_32' id='input_3_32' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' ><\/option><option value='maison unifamiliale' >maison unifamiliale<\/option><option value='semi-detach\u00e9e (une seule unit\u00e9)' >semi-detach\u00e9e (une seule unit\u00e9)<\/option><option value='Duplex (une seule unit\u00e9)' >Duplex (une seule unit\u00e9)<\/option><option value='Maison en rang\u00e9e (une seule unit\u00e9)' >Maison en rang\u00e9e (une seule unit\u00e9)<\/option><option value='maison mobile' >maison mobile<\/option><option value='unit\u00e9 condominiale' >unit\u00e9 condominiale<\/option><option value='Unit\u00e9s multiples (veuillez donner plus de d\u00e9tails)' >Unit\u00e9s multiples (veuillez donner plus de d\u00e9tails)<\/option><option value='Autre (veuillez donner plus de d\u00e9tails)' >Autre (veuillez donner plus de d\u00e9tails)<\/option><\/select><\/div><\/div><div id=\"field_3_34\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_34'>Veuillez fournir des d\u00e9tails:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_34' id='input_3_34' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <input type='button' id='gform_previous_button_3_68' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='pr\u00e9c\u00e9dent'  \/> <input type='button' id='gform_next_button_3_68' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_6' class='gform_page' data-js='page-field-id-68' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_6' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_70\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Au sujet de votre transaction<\/h3><\/div><div id=\"field_3_67\" class=\"gfield gfield--type-select gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_67'>Achetez-vous cette propri\u00e9t\u00e9 en vue de l\u2019utiliser comme votre r\u00e9sidence principale?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_67' id='input_3_67' class='large gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='' ><\/option><option value='Oui' >Oui<\/option><option value='Non' >Non<\/option><\/select><\/div><\/div><fieldset id=\"field_3_37\" class=\"gfield gfield--type-checkbox gfield--type-choice gf_list_inline gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Sinon, veuillez s\u2019il vous plait indiquer qui habitera dans la r\u00e9sidence (veuillez s\u00e9lectionner toutes les options applicables):<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_3_37'><div class='gchoice gchoice_3_37_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_37.1' type='checkbox'  value='un membre de famille imm\u00e9diat'  id='choice_3_37_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_37_1' id='label_3_37_1' class='gform-field-label gform-field-label--type-inline'>un membre de famille imm\u00e9diat<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_37_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_37.2' type='checkbox'  value='locataires'  id='choice_3_37_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_37_2' id='label_3_37_2' class='gform-field-label gform-field-label--type-inline'>locataires<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_37_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_37.3' type='checkbox'  value='moi-m\u00eame, mais en tant que r\u00e9sidence secondaire'  id='choice_3_37_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_37_3' id='label_3_37_3' class='gform-field-label gform-field-label--type-inline'>moi-m\u00eame, mais en tant que r\u00e9sidence secondaire<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_37_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_37.4' type='checkbox'  value='la propri\u00e9t\u00e9 sera vacante'  id='choice_3_37_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_37_4' id='label_3_37_4' class='gform-field-label gform-field-label--type-inline'>la propri\u00e9t\u00e9 sera vacante<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_37_5'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_37.5' type='checkbox'  value='autre'  id='choice_3_37_5'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_37_5' id='label_3_37_5' class='gform-field-label gform-field-label--type-inline'>autre<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><\/fieldset><div id=\"field_3_38\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_38'>Expliquez s&#039;il vous plait:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_38' id='input_3_38' class='textarea small'     aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_3_75\" class=\"gfield gfield--type-address gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Si cette propri\u00e9t\u00e9 ne sera pas votre r\u00e9sidence principale, veuillez fournier votre adresse de r\u00e9exp\u00e9dition:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend>    \n                    <div class='ginput_complex ginput_container has_street has_street2 has_city has_state has_zip has_country ginput_container_address gform-grid-row' id='input_3_75' >\n                         <span class='ginput_full address_line_1 ginput_address_line_1 gform-grid-col' id='input_3_75_1_container' >\n                                        <input type='text' name='input_75.1' id='input_3_75_1' value=''    aria-required='true'    \/>\n                                        <label for='input_3_75_1' id='input_3_75_1_label' class='gform-field-label gform-field-label--type-sub '>Adresse postale<\/label>\n                                    <\/span><span class='ginput_full address_line_2 ginput_address_line_2 gform-grid-col' id='input_3_75_2_container' >\n                                        <input type='text' name='input_75.2' id='input_3_75_2' value=''     aria-required='false'   \/>\n                                        <label for='input_3_75_2' id='input_3_75_2_label' class='gform-field-label gform-field-label--type-sub '>Adresse ligne 2<\/label>\n                                    <\/span><span class='ginput_left address_city ginput_address_city gform-grid-col' id='input_3_75_3_container' >\n                                    <input type='text' name='input_75.3' id='input_3_75_3' value=''    aria-required='true'    \/>\n                                    <label for='input_3_75_3' id='input_3_75_3_label' class='gform-field-label gform-field-label--type-sub '>Ville<\/label>\n                                 <\/span><span class='ginput_right address_state ginput_address_state gform-grid-col' id='input_3_75_4_container' >\n                                        <input type='text' name='input_75.4' id='input_3_75_4' value=''      aria-required='true'    \/>\n                                        <label for='input_3_75_4' id='input_3_75_4_label' class='gform-field-label gform-field-label--type-sub '>\u00c9tat\/Province\/R\u00e9gion<\/label>\n                                      <\/span><span class='ginput_left address_zip ginput_address_zip gform-grid-col' id='input_3_75_5_container' >\n                                    <input type='text' name='input_75.5' id='input_3_75_5' value=''    aria-required='true'    \/>\n                                    <label for='input_3_75_5' id='input_3_75_5_label' class='gform-field-label gform-field-label--type-sub '>Code postal<\/label>\n                                <\/span><span class='ginput_right address_country ginput_address_country gform-grid-col' id='input_3_75_6_container' >\n                                        <select name='input_75.6' id='input_3_75_6'   aria-required='true'    ><option value='' selected='selected'><\/option><option value='Afghanistan' >Afghanistan<\/option><option value='Afrique du Sud' >Afrique du Sud<\/option><option value='Albanie' >Albanie<\/option><option value='Alg\u00e9rie' >Alg\u00e9rie<\/option><option value='Allemagne' >Allemagne<\/option><option value='Andorre' >Andorre<\/option><option value='Angola' >Angola<\/option><option value='Anguilla' >Anguilla<\/option><option value='Antarctique' >Antarctique<\/option><option value='Antigua-et-Barbuda' >Antigua-et-Barbuda<\/option><option value='Arabie Saoudite' >Arabie Saoudite<\/option><option value='Argentine' >Argentine<\/option><option value='Arm\u00e9nie' >Arm\u00e9nie<\/option><option value='Aruba' >Aruba<\/option><option value='Australie' >Australie<\/option><option value='Autriche' >Autriche<\/option><option value='Azerba\u00efdjan' >Azerba\u00efdjan<\/option><option value='Bahamas' >Bahamas<\/option><option value='Bahre\u00efn' >Bahre\u00efn<\/option><option value='Bangladesh' >Bangladesh<\/option><option value='Belarus' >Belarus<\/option><option value='Belgique' >Belgique<\/option><option value='Belize' >Belize<\/option><option value='Bermudes' >Bermudes<\/option><option value='Bhoutan' >Bhoutan<\/option><option value='Bolivie' >Bolivie<\/option><option value='Bonaire, Saint-Eustache et Saba' >Bonaire, Saint-Eustache et Saba<\/option><option value='Bosnie-Herz\u00e9govine' >Bosnie-Herz\u00e9govine<\/option><option value='Botswana' >Botswana<\/option><option value='Brunei Darussalam' >Brunei Darussalam<\/option><option value='Br\u00e9sil' >Br\u00e9sil<\/option><option value='Bulgarie' >Bulgarie<\/option><option value='Burkina Faso' >Burkina Faso<\/option><option value='Burundi' >Burundi<\/option><option value='B\u00e9nin' >B\u00e9nin<\/option><option value='Cambodge' >Cambodge<\/option><option value='Cameroun' >Cameroun<\/option><option value='Canada' >Canada<\/option><option value='Cap-Vert' >Cap-Vert<\/option><option value='Chili' >Chili<\/option><option value='Chine' >Chine<\/option><option value='Chypre' >Chypre<\/option><option value='Colombie' >Colombie<\/option><option value='Comores' >Comores<\/option><option value='Congo' >Congo<\/option><option value='Cor\u00e9e (R\u00e9publique de)' >Cor\u00e9e (R\u00e9publique de)<\/option><option value='Cor\u00e9e (R\u00e9publique populaire d\u00e9mocratique de)' >Cor\u00e9e (R\u00e9publique populaire d\u00e9mocratique de)<\/option><option value='Costa Rica' >Costa Rica<\/option><option value='Croatie' >Croatie<\/option><option value='Cuba' >Cuba<\/option><option value='Cura\u00e7ao' >Cura\u00e7ao<\/option><option value='C\u00f4te d\u2019Ivoire' >C\u00f4te d\u2019Ivoire<\/option><option value='Danemark' >Danemark<\/option><option value='Djibouti' >Djibouti<\/option><option value='Dominique' >Dominique<\/option><option value='Espagne' >Espagne<\/option><option value='Estonie' >Estonie<\/option><option value='Eswatini' >Eswatini<\/option><option value='Fidji' >Fidji<\/option><option value='Finlande' >Finlande<\/option><option value='France' >France<\/option><option value='F\u00e9d\u00e9ration Russe' >F\u00e9d\u00e9ration Russe<\/option><option value='Gabon' >Gabon<\/option><option value='Gambie' >Gambie<\/option><option value='Ghana' >Ghana<\/option><option value='Gibraltar' >Gibraltar<\/option><option value='Grenade' >Grenade<\/option><option value='Groenland' >Groenland<\/option><option value='Gr\u00e8ce' >Gr\u00e8ce<\/option><option value='Guadeloupe' >Guadeloupe<\/option><option value='Guam' >Guam<\/option><option value='Guatemala' >Guatemala<\/option><option value='Guernsey' >Guernsey<\/option><option value='Guin\u00e9e' >Guin\u00e9e<\/option><option value='Guin\u00e9e \u00e9quatoriale' >Guin\u00e9e \u00e9quatoriale<\/option><option value='Guin\u00e9e-Bissau' >Guin\u00e9e-Bissau<\/option><option value='Guyane' >Guyane<\/option><option value='Guyane' >Guyane<\/option><option value='G\u00e9orgie' >G\u00e9orgie<\/option><option value='G\u00e9orgie du Sud et \u00celes Sandwich du Sud' >G\u00e9orgie du Sud et \u00celes Sandwich du Sud<\/option><option value='Ha\u00efti' >Ha\u00efti<\/option><option value='Honduras' >Honduras<\/option><option value='Hong Kong' >Hong Kong<\/option><option value='Hongrie' >Hongrie<\/option><option value='Inde' >Inde<\/option><option value='Indon\u00e9sie' >Indon\u00e9sie<\/option><option value='Irak' >Irak<\/option><option value='Iran' >Iran<\/option><option value='Irlande' >Irlande<\/option><option value='Islande' >Islande<\/option><option value='Isra\u00ebl' >Isra\u00ebl<\/option><option value='Italie' >Italie<\/option><option value='Jama\u00efque' >Jama\u00efque<\/option><option value='Japon' >Japon<\/option><option value='Jersey' >Jersey<\/option><option value='Jordanie' >Jordanie<\/option><option value='Kazakhstan' >Kazakhstan<\/option><option value='Kenya' >Kenya<\/option><option value='Kirghizistan' >Kirghizistan<\/option><option value='Kiribati' >Kiribati<\/option><option value='Kowe\u00eft' >Kowe\u00eft<\/option><option value='La Barbade' >La Barbade<\/option><option value='La R\u00e9union' >La R\u00e9union<\/option><option value='Lesotho' >Lesotho<\/option><option value='Lettonie' >Lettonie<\/option><option value='Liban' >Liban<\/option><option value='Liberia' >Liberia<\/option><option value='Libye' >Libye<\/option><option value='Liechtenstein' >Liechtenstein<\/option><option value='Lituanie' >Lituanie<\/option><option value='Luxembourg' >Luxembourg<\/option><option value='Macao' >Macao<\/option><option value='Mac\u00e9doine du Nord' >Mac\u00e9doine du Nord<\/option><option value='Madagascar' >Madagascar<\/option><option value='Malaisie' >Malaisie<\/option><option value='Malawi' >Malawi<\/option><option value='Maldives' >Maldives<\/option><option value='Mali' >Mali<\/option><option value='Malte' >Malte<\/option><option value='Maroc' >Maroc<\/option><option value='Martinique' >Martinique<\/option><option value='Mauritanie' >Mauritanie<\/option><option value='Mayotte' >Mayotte<\/option><option value='Mexique' >Mexique<\/option><option value='Micron\u00e9sie' >Micron\u00e9sie<\/option><option value='Moldavie' >Moldavie<\/option><option value='Monaco' >Monaco<\/option><option value='Mongolie' >Mongolie<\/option><option value='Montserrat' >Montserrat<\/option><option value='Mont\u00e9n\u00e9gro' >Mont\u00e9n\u00e9gro<\/option><option value='Mozambique' >Mozambique<\/option><option value='Myanmar' >Myanmar<\/option><option value='Namibie' >Namibie<\/option><option value='Nauru' >Nauru<\/option><option value='Nicaragua' >Nicaragua<\/option><option value='Niger' >Niger<\/option><option value='Nig\u00e9ria' >Nig\u00e9ria<\/option><option value='Niu\u00e9' >Niu\u00e9<\/option><option value='Norv\u00e8ge' >Norv\u00e8ge<\/option><option value='Nouvelle-Cal\u00e9donie' >Nouvelle-Cal\u00e9donie<\/option><option value='Nouvelle-Z\u00e9lande' >Nouvelle-Z\u00e9lande<\/option><option value='N\u00e9pal' >N\u00e9pal<\/option><option value='Oman' >Oman<\/option><option value='Ouganda' >Ouganda<\/option><option value='Ouzb\u00e9kistan' >Ouzb\u00e9kistan<\/option><option value='Pakistan' >Pakistan<\/option><option value='Palau' >Palau<\/option><option value='Panama' >Panama<\/option><option value='Papouasie-Nouvelle-Guin\u00e9e' >Papouasie-Nouvelle-Guin\u00e9e<\/option><option value='Paraguay' >Paraguay<\/option><option value='Pays-Bas' >Pays-Bas<\/option><option value='Philippines' >Philippines<\/option><option value='Pologne' >Pologne<\/option><option value='Polyn\u00e9sie fran\u00e7aise' >Polyn\u00e9sie fran\u00e7aise<\/option><option value='Porto Rico' >Porto Rico<\/option><option value='Portugal' >Portugal<\/option><option value='P\u00e9rou' >P\u00e9rou<\/option><option value='Qatar' >Qatar<\/option><option value='Roumanie' >Roumanie<\/option><option value='Royaume-Uni' >Royaume-Uni<\/option><option value='Rwanda' >Rwanda<\/option><option value='R\u00e9publique Dominicaine' >R\u00e9publique Dominicaine<\/option><option value='R\u00e9publique Tch\u00e8que' >R\u00e9publique Tch\u00e8que<\/option><option value='R\u00e9publique arabe syrienne' >R\u00e9publique arabe syrienne<\/option><option value='R\u00e9publique centrafricaine' >R\u00e9publique centrafricaine<\/option><option value='R\u00e9publique d\u00e9mocratique du Congo' >R\u00e9publique d\u00e9mocratique du Congo<\/option><option value='R\u00e9publique d\u00e9mocratique populaire du Laos' >R\u00e9publique d\u00e9mocratique populaire du Laos<\/option><option value='Sahara occidental' >Sahara occidental<\/option><option value='Saint Barth\u00e9lemy' >Saint Barth\u00e9lemy<\/option><option value='Saint Martin' >Saint Martin<\/option><option value='Saint Pierre et Miquelon' >Saint Pierre et Miquelon<\/option><option value='Saint-Christophe-et-Nevis' >Saint-Christophe-et-Nevis<\/option><option value='Saint-Marin' >Saint-Marin<\/option><option value='Saint-Si\u00e8ge' >Saint-Si\u00e8ge<\/option><option value='Saint-Vincent-et-les Grenadines' >Saint-Vincent-et-les Grenadines<\/option><option value='Sainte-H\u00e9l\u00e8ne, Ascension et Tristan da Cunha' >Sainte-H\u00e9l\u00e8ne, Ascension et Tristan da Cunha<\/option><option value='Sainte-Lucie' >Sainte-Lucie<\/option><option value='Salvador' >Salvador<\/option><option value='Samoa' >Samoa<\/option><option value='Samoa am\u00e9ricaines' >Samoa am\u00e9ricaines<\/option><option value='Sao Tom\u00e9 et Principe' >Sao Tom\u00e9 et Principe<\/option><option value='Serbie' >Serbie<\/option><option value='Seychelles' >Seychelles<\/option><option value='Sierra Leone' >Sierra Leone<\/option><option value='Singapour' >Singapour<\/option><option value='Sint Maarten' >Sint Maarten<\/option><option value='Slovaquie' >Slovaquie<\/option><option value='Slov\u00e9nie' >Slov\u00e9nie<\/option><option value='Somalie' >Somalie<\/option><option value='Soudan' >Soudan<\/option><option value='Soudan du Sud' >Soudan du Sud<\/option><option value='Sri Lanka' >Sri Lanka<\/option><option value='Suisse' >Suisse<\/option><option value='Suriname' >Suriname<\/option><option value='Su\u00e8de' >Su\u00e8de<\/option><option value='S\u00e9n\u00e9gal' >S\u00e9n\u00e9gal<\/option><option value='Tadjikistan' >Tadjikistan<\/option><option value='Tanzanie (R\u00e9publique-Unie de)' >Tanzanie (R\u00e9publique-Unie de)<\/option><option value='Ta\u00efwan' >Ta\u00efwan<\/option><option value='Tchad' >Tchad<\/option><option value='Terres Australes Fran\u00e7aises' >Terres Australes Fran\u00e7aises<\/option><option value='Territoire britannique de l\u2019oc\u00e9an Indien' >Territoire britannique de l\u2019oc\u00e9an Indien<\/option><option value='Tha\u00eflande' >Tha\u00eflande<\/option><option value='Timor oriental' >Timor oriental<\/option><option value='Togo' >Togo<\/option><option value='Tokelau' >Tokelau<\/option><option value='Tonga' >Tonga<\/option><option value='Trinit\u00e9 et Tobago' >Trinit\u00e9 et Tobago<\/option><option value='Tunisie' >Tunisie<\/option><option value='Turkm\u00e9nistan' >Turkm\u00e9nistan<\/option><option value='Turquie' >Turquie<\/option><option value='Tuvalu' >Tuvalu<\/option><option value='Ukraine' >Ukraine<\/option><option value='Uruguay' >Uruguay<\/option><option value='Vanuatu' >Vanuatu<\/option><option value='Venezuela' >Venezuela<\/option><option value='Vietnam' >Vietnam<\/option><option value='Wallis et Futuna' >Wallis et Futuna<\/option><option value='Y\u00e9men' >Y\u00e9men<\/option><option value='Zambie' >Zambie<\/option><option value='Zimbabwe' >Zimbabwe<\/option><option value='\u00c9gypte' >\u00c9gypte<\/option><option value='\u00c9mirats arabes unis' >\u00c9mirats arabes unis<\/option><option value='\u00c9quateur' >\u00c9quateur<\/option><option value='\u00c9rythr\u00e9e' >\u00c9rythr\u00e9e<\/option><option value='\u00c9tat palestinien' >\u00c9tat palestinien<\/option><option value='\u00c9tats-Unis' >\u00c9tats-Unis<\/option><option value='\u00c9thiopie' >\u00c9thiopie<\/option><option value='\u00cele Bouvet' >\u00cele Bouvet<\/option><option value='\u00cele Christmas' >\u00cele Christmas<\/option><option value='\u00cele Maurice' >\u00cele Maurice<\/option><option value='\u00cele Norfolk' >\u00cele Norfolk<\/option><option value='\u00cele de Man' >\u00cele de Man<\/option><option value='\u00celes Cayman' >\u00celes Cayman<\/option><option value='\u00celes Cocos' >\u00celes Cocos<\/option><option value='\u00celes Cook' >\u00celes Cook<\/option><option value='\u00celes Falkland' >\u00celes Falkland<\/option><option value='\u00celes F\u00e9ro\u00e9' >\u00celes F\u00e9ro\u00e9<\/option><option value='\u00celes Heard et McDonald' >\u00celes Heard et McDonald<\/option><option value='\u00celes Mariannes du Nord' >\u00celes Mariannes du Nord<\/option><option value='\u00celes Marshall' >\u00celes Marshall<\/option><option value='\u00celes Pitcairn' >\u00celes Pitcairn<\/option><option value='\u00celes Salomon' >\u00celes Salomon<\/option><option value='\u00celes Turques et Ca\u00efques' >\u00celes Turques et Ca\u00efques<\/option><option value='\u00celes Vierges am\u00e9ricaines' >\u00celes Vierges am\u00e9ricaines<\/option><option value='\u00celes Vierges britanniques' >\u00celes Vierges britanniques<\/option><option value='\u00celes de Svalbard et Jan Mayen' >\u00celes de Svalbard et Jan Mayen<\/option><option value='\u00celes mineures am\u00e9ricaines' >\u00celes mineures am\u00e9ricaines<\/option><option value='\u00celes \u00c5land' >\u00celes \u00c5land<\/option><\/select>\n                                        <label for='input_3_75_6' id='input_3_75_6_label' class='gform-field-label gform-field-label--type-sub '>Pays<\/label>\n                                    <\/span>\n                    <div class='gf_clear gf_clear_complex'><\/div>\n                <\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <input type='button' id='gform_previous_button_3_61' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='pr\u00e9c\u00e9dent'  \/> <input type='button' id='gform_next_button_3_61' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_7' class='gform_page' data-js='page-field-id-61' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_7' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_60\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Au sujet de votre transaction<\/h3><\/div><fieldset id=\"field_3_39\" class=\"gfield gfield--type-checkbox gfield--type-choice gfield--width-full gf_list_inline gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Aurez-vous besoin de financement pour compl\u00e9ter votre achat (veuillez s\u00e9lectionner toutes les options applicables)?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_checkbox'><div class='gfield_checkbox ' id='input_3_39'><div class='gchoice gchoice_3_39_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_39.1' type='checkbox'  value='Hypoth\u00e8que'  id='choice_3_39_1'   aria-describedby=\"gfield_description_3_39\"\/>\n\t\t\t\t\t\t\t\t<label for='choice_3_39_1' id='label_3_39_1' class='gform-field-label gform-field-label--type-inline'>Hypoth\u00e8que<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_39_2'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_39.2' type='checkbox'  value='Nouvelle ligne de cr\u00e9dit (\u00e0 \u00e8tre enregistr\u00e9e sur la nouvelle propri\u00e9t\u00e9)'  id='choice_3_39_2'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_39_2' id='label_3_39_2' class='gform-field-label gform-field-label--type-inline'>Nouvelle ligne de cr\u00e9dit (\u00e0 \u00e8tre enregistr\u00e9e sur la nouvelle propri\u00e9t\u00e9)<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_39_3'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_39.3' type='checkbox'  value='Pr\u00eat priv\u00e9'  id='choice_3_39_3'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_39_3' id='label_3_39_3' class='gform-field-label gform-field-label--type-inline'>Pr\u00eat priv\u00e9<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_39_4'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_39.4' type='checkbox'  value='pr\u00eatpont (ou \u00ab pr\u00eat-relais \u00bb)'  id='choice_3_39_4'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_39_4' id='label_3_39_4' class='gform-field-label gform-field-label--type-inline'>pr\u00eatpont (ou \u00ab pr\u00eat-relais \u00bb)<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_39_5'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_39.5' type='checkbox'  value='aucun financement requis'  id='choice_3_39_5'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_39_5' id='label_3_39_5' class='gform-field-label gform-field-label--type-inline'>aucun financement requis<\/label>\n\t\t\t\t\t\t\t<\/div><div class='gchoice gchoice_3_39_6'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_39.6' type='checkbox'  value='autre'  id='choice_3_39_6'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_3_39_6' id='label_3_39_6' class='gform-field-label gform-field-label--type-inline'>autre<\/label>\n\t\t\t\t\t\t\t<\/div><\/div><\/div><div class='gfield_description' id='gfield_description_3_39'>(Un pr\u00eat-pont, ou pr\u00eat-relais, est un financement temporaire con\u00e7u pour aider les propri\u00e9taires \u00e0 combler le d\u00e9calage entre la vente de leur maison actuelle et l\u2019achat de leur nouvelle maison. Cette situation s\u2019applique principalement lorsque vous d\u00e9sirez acheter une nouvelle propri\u00e9t\u00e9 avant d\u2019avoir conclu la vente de votre propri\u00e9t\u00e9 existante, mais avez besoin d\u2019acc\u00e9der \u00e0 la valeur nette de votre vente afin de compl\u00e9ter l\u2019achat).<\/div><\/fieldset><div id=\"field_3_40\" class=\"gfield gfield--type-textarea gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_40'>Expliquez s&#039;il vous plait:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_40' id='input_3_40' class='textarea small'     aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_3_71\" class=\"gfield gfield--type-list gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Veuillez nous fournir l\u2019information suivante pour chaque plan de financement:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_list ginput_list ginput_container_list--columns'><div class='gfield_list gfield_list_container'><div class=\"gfield_list_header gform-grid-row\"><div class=\"gform-field-label gfield_header_item gform-grid-col\">Nom de la banque \/ du preteur:<\/div><div class=\"gform-field-label gfield_header_item gform-grid-col\">Nom de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:<\/div><div class=\"gform-field-label gfield_header_item gform-grid-col\">Num\u00e9ro de t\u00e9l\u00e9phone de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:<\/div><div class=\"gform-field-label gfield_header_item gform-grid-col\">Commentaires:<\/div><div class=\"gfield_header_item gfield_header_item--icons gform-grid-col\">&nbsp;<\/div><\/div><div class=\"gfield_list_groups\"><div class='gfield_list_row_odd gfield_list_group gform-grid-row'><div class='gfield_list_group_item gfield_list_cell gfield_list_71_cell1 gform-grid-col' data-label='Nom de la banque \/ du preteur:'><input aria-invalid='false' aria-required=\"true\"  aria-label='Nom de la banque \/ du preteur:, Ligne 1' data-aria-label-template='Nom de la banque \/ du preteur:, Ligne {0}' type='text' name='input_71[]' value=''   \/><\/div><div class='gfield_list_group_item gfield_list_cell gfield_list_71_cell2 gform-grid-col' data-label='Nom de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:'><input aria-invalid='false' aria-required=\"true\"  aria-label='Nom de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:, Ligne 1' data-aria-label-template='Nom de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:, Ligne {0}' type='text' name='input_71[]' value=''   \/><\/div><div class='gfield_list_group_item gfield_list_cell gfield_list_71_cell3 gform-grid-col' data-label='Num\u00e9ro de t\u00e9l\u00e9phone de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:'><input aria-invalid='false' aria-required=\"true\"  aria-label='Num\u00e9ro de t\u00e9l\u00e9phone de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:, Ligne 1' data-aria-label-template='Num\u00e9ro de t\u00e9l\u00e9phone de votre courtier ou sp\u00e9cialiste hypoth\u00e9caire:, Ligne {0}' type='text' name='input_71[]' value=''   \/><\/div><div class='gfield_list_group_item gfield_list_cell gfield_list_71_cell4 gform-grid-col' data-label='Commentaires:'><input aria-invalid='false' aria-required=\"true\"  aria-label='Commentaires:, Ligne 1' data-aria-label-template='Commentaires:, Ligne {0}' type='text' name='input_71[]' value=''   \/><\/div><div class='gfield_list_icons gform-grid-col'>   <button type='button'  class='add_list_item ' aria-label='Ajouter une autre ligne' onclick='gformAddListItem(this, 0)'>Ajouter<\/button>   <button type='button'  class='delete_list_item' aria-label='Supprimer la ligne 1' data-aria-label-template='Supprimer la ligne {0}' onclick='gformDeleteListItem(this, 0)' style=\"visibility:hidden;\">Retirer<\/button><\/div><\/div><\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <input type='button' id='gform_previous_button_3_78' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='pr\u00e9c\u00e9dent'  \/> <input type='button' id='gform_next_button_3_78' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_8' class='gform_page' data-js='page-field-id-78' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_8' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_42\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Optionnel<\/h3><\/div><div id=\"field_3_43\" class=\"gfield gfield--type-select field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_43'>Comment avez-vous pris connaissance de notre cabinet?<\/label><div class='ginput_container ginput_container_select'><select name='input_43' id='input_3_43' class='large gfield_select'     aria-invalid=\"false\" ><option value='' ><\/option><option value='agent immobilier' >agent immobilier<\/option><option value='constructeur' >constructeur<\/option><option value='recherche internet' >recherche internet<\/option><option value='r\u00e9f\u00e9rence d\u2019amis ou famille' >r\u00e9f\u00e9rence d\u2019amis ou famille<\/option><option value='ancien client de Louis Guertin' >ancien client de Louis Guertin<\/option><option value='client existant de Guertin Poirier' >client existant de Guertin Poirier<\/option><option value='autre' >autre<\/option><\/select><\/div><\/div><div id=\"field_3_44\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_44'>Expliquez s&#039;il vous plait:<\/label><div class='ginput_container ginput_container_text'><input name='input_44' id='input_3_44' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_3_45\" class=\"gfield gfield--type-select field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_45'>Quelle est la langue favoris\u00e9e pour toutes correspondances avec notre bureau?<\/label><div class='ginput_container ginput_container_select'><select name='input_45' id='input_3_45' class='large gfield_select'     aria-invalid=\"false\" ><option value='' ><\/option><option value='anglais' >anglais<\/option><option value='fran\u00e7ais' >fran\u00e7ais<\/option><\/select><\/div><\/div><div id=\"field_3_46\" class=\"gfield gfield--type-textarea field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_46'>Avez-vous des commentaires concernant nos services ou des instructions sp\u00e9ciales vis-\u00e0-vis de votre transaction?<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_46' id='input_3_46' class='textarea small'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><\/div>\n                    <\/div>\n                    <div class='gform-page-footer gform_page_footer top_label'>\n                        <input type='button' id='gform_previous_button_3_56' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='Pr\u00e9c\u00e9dent'  \/> <input type='button' id='gform_next_button_3_56' class='gform_next_button gform-theme-button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='next' value='Suivant'  \/> \n                    <\/div>\n                <\/div>\n                <div id='gform_page_3_9' class='gform_page' data-js='page-field-id-56' style='display:none;'>\n                    <div class='gform_page_fields'>\n                        <div id='gform_fields_3_9' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_3_47\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\">Documents \u00e0 l\u2019appui<\/h3><\/div><div id=\"field_3_72\" class=\"gfield gfield--type-html gfield--width-full gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><strong>Veuillez noter que nous exigerons une copie des documents suivants d\u00e8s que possible pour pr\u00e9parer votre dossier. Vous pouvez amener ces documents avec vous au moment de votre rendez-vous afin que l\u2019on puisse faire une copie pour votre dossier.  Vous pouvez \u00e9galement choisir d\u2019envoyer des copies num\u00e9ris\u00e9es par <a href=\"mailto:opendoor@guertinpoirierlaw.ca\">courriel<\/a> ou par t\u00e9l\u00e9copieur au (613) 744-3173.<\/strong><\/div><div id=\"field_3_73\" class=\"gfield gfield--type-html gfield--width-full gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><p><strong>Identification<\/strong><\/p>\n<p>Deux (2) pi\u00e8ces d'identit\u00e9 (recto-verso) pour chaque individu qui sera enregistr\u00e9 sur le titre de la propri\u00e9t\u00e9. Les pi\u00e8ces d'identit\u00e9 acceptable, en ordre de pr\u00e9f\u00e9rence:<\/p>\n<ul>\n<li>Passeport Canadien<\/li>\n<li>Carte de r\u00e9sident permanent<\/li>\n<li>Permis de conduire<\/li>\n<li>Certificat de naissance Canadien<\/li>\n<li>Carte de cr\u00e9dit majeure (doit \u00eatre sign\u00e9e et valide, pas expir\u00e9e)<\/li>\n<li>Carte Nexus<\/li>\n<\/ul>\n<p>Nous exigeons au moins une pi\u00e8ce d'identit\u00e9 avec photo. Veuillez noter que la carte de sant\u00e9 (OHIP) ne peut pas \u00eatre accept\u00e9e en ce moment.<\/p>\n<p><strong>Autres documents<\/strong><\/p>\n<ul>\n<li>Une copie compl\u00e8te de votre <strong>Convention d\u2019Achat-Vente<\/strong> (\u00ab Agreement of Purchase and Sale \u00bb). Si vous ne d\u00e9tenez pas de copie compl\u00e8te incluant tous les amendements ou annexes, veuillez s\u2019il vous plait demander \u00e0 votre agent de nous en acheminer une copie par courriel.<\/li>\n<\/ul>\n<\/div><\/div><\/div>\n        <div class='gform-page-footer gform_page_footer top_label'><input type='submit' id='gform_previous_button_3' class='gform_previous_button gform-theme-button gform-theme-button--secondary button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='previous' value='pr\u00e9c\u00e9dent'  \/> <input type='submit' id='gform_submit_button_3' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Soumettre'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_3' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_3' id='gform_theme_3' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_3' id='gform_style_settings_3' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_3' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='3' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='CAD' value='tW2eOfN+1L9o6IFMjauDCDpTTyY76UFd9JI6YE7oagvCC2Oe42GdL2PnijWIZKEZckz1hInJRLytVkxAsczOfZugkmJhjgRpZ3iuTg6ioyPbvEE=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_3' value='WyJ7XCI3OVwiOltcIjJkN2RhNWFkYTQ3NWM2OWYwODVjNmMzMDBkMzYxNmRkXCIsXCJiZTI5ODE0ZTljZDM5MWI4ZTM1MTcxYWM2MWRhNGZjOVwiLFwiMjI3MWNmZGY1ZThkOWY4YTlkNGNlZWY0M2RhMDNkZjBcIl0sXCI4NVwiOltcIjJkN2RhNWFkYTQ3NWM2OWYwODVjNmMzMDBkMzYxNmRkXCIsXCIxOWM5NWFkMDEyYzc0NDQ1ODUxZjJjMzM4ZGI1Y2I5MlwiLFwiMjM1MjY1Yjg3MGU3MzExNTBhZTk4NTMyYTlmYTBlODhcIixcImNjNmNiYTJiNjNiNWU0MGYwNGJlMGMxNjk1YzFjMTExXCJdLFwiODhcIjpbXCIyZDdkYTVhZGE0NzVjNjlmMDg1YzZjMzAwZDM2MTZkZFwiLFwiYjBkZTU1MzhjMGUyYjNiNTA3ZTNiMTIxMmQ5YTYxNWZcIixcIjQ5ZDYzM2M1YmZlNTc4ZTJlMDIyNDU3OTI2ZGI4ZWY1XCJdfSIsImM3YmUxNjNhM2QyMjYzOGI4Y2M3MTkyYTg0ZTJiM2I2Il0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_3' id='gform_target_page_number_3' value='2' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_3' id='gform_source_page_number_3' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n             <\/div><\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 3, 'https:\/\/guertinpoirierlaw.ca\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_3').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_3');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_3').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){form_content.find('form').css('opacity', 0);jQuery('#gform_wrapper_3').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_3').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_3').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_3').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_3').val();gformInitSpinner( 3, 'https:\/\/guertinpoirierlaw.ca\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [3, current_page]);window['gf_submitting_3'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_3').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_3').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [3]);window['gf_submitting_3'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_3').text());}else{jQuery('#gform_3').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"3\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_3\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_3\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_3\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 3, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":232,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1037","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/pages\/1037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/comments?post=1037"}],"version-history":[{"count":5,"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/pages\/1037\/revisions"}],"predecessor-version":[{"id":1171,"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/pages\/1037\/revisions\/1171"}],"up":[{"embeddable":true,"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/pages\/232"}],"wp:attachment":[{"href":"https:\/\/guertinpoirierlaw.ca\/fr\/wp-json\/wp\/v2\/media?parent=1037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}